{"id":11694,"date":"2022-09-28T16:42:05","date_gmt":"2022-09-28T07:42:05","guid":{"rendered":"https:\/\/prodskill.com\/?p=11694"},"modified":"2022-10-10T21:01:58","modified_gmt":"2022-10-10T12:01:58","slug":"da-macro-function-common-entity-get-set","status":"publish","type":"post","link":"https:\/\/prodskill.com\/es\/da-macro-function-common-entity-get-set\/","title":{"rendered":"Macro DA# (2): Funci\u00f3n macro DA# (1) - Funci\u00f3n com\u00fan, Entidad Get\/Set"},"content":{"rendered":"<p>En este art\u00edculo, se revisar\u00e1 la funci\u00f3n com\u00fan de macro Da# Entity Get\/Set.<\/p>\n\n\n\n<p>Esta es una continuaci\u00f3n del art\u00edculo anterior.<\/p>\n\n\n\n<p><a href=\"https:\/\/prodskill.com\/es\/da-macro-overview\/\">Macro DA#(1): DA#, API DA#, descripci\u00f3n general de la macro DA#<\/a><\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">&lt;&lt;Tabla de contenidos&gt;&gt;<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Pesta\u00f1a de contenido alternativo\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Palanca<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/prodskill.com\/es\/da-macro-function-common-entity-get-set\/#2_DA_Macro_%EA%B8%B0%EB%8A%A5\" >2. Funci\u00f3n macro DA#<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/prodskill.com\/es\/da-macro-function-common-entity-get-set\/#21_DA_Macro_%EA%B3%B5%ED%86%B5_%EA%B8%B0%EB%8A%A5\" >2.1. Funciones comunes de la macro DA#<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/prodskill.com\/es\/da-macro-function-common-entity-get-set\/#211_Select_Model%EB%AA%A8%EB%8D%B8_%EC%84%A0%ED%83%9D\" >2.1.1. Seleccionar modelo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/prodskill.com\/es\/da-macro-function-common-entity-get-set\/#212_Clear_List\" >2.1.2. Limpiar lista<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/prodskill.com\/es\/da-macro-function-common-entity-get-set\/#22_DA_Macro_Entity_GetSet\" >2.2. DA# Macro Entidad Obtener\/Establecer<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/prodskill.com\/es\/da-macro-function-common-entity-get-set\/#221_Entity_Get\" >2.2.1. Obtener entidad<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/prodskill.com\/es\/da-macro-function-common-entity-get-set\/#222_Entity_Set\" >2.2.2. Conjunto de entidades<\/a><\/li><\/ul><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\" id=\"2._DA#_Macro_\uae30\ub2a5\"><span class=\"ez-toc-section\" id=\"2_DA_Macro_%EA%B8%B0%EB%8A%A5\"><\/span>2. Funci\u00f3n macro DA#<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>La funci\u00f3n de macro DA# se divide en gran medida en funciones comunes, Obtener\/Establecer entidad, Obtener\/Establecer atributo e Invertir.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"2.1._\uacf5\ud1b5_\uae30\ub2a5\"><span class=\"ez-toc-section\" id=\"21_DA_Macro_%EA%B3%B5%ED%86%B5_%EA%B8%B0%EB%8A%A5\"><\/span>2.1. Funciones comunes de la macro DA#<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-218.png\"><img loading=\"lazy\" decoding=\"async\" width=\"210\" height=\"36\" src=\"https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-218.png\" alt=\"DA# Macro: \uacf5\ud1b5\uae30\ub2a5 \ubc84\ud2bc\" class=\"wp-image-11695\" srcset=\"https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-218.png 210w, https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-218-18x3.png 18w, https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-218-24x4.png 24w, https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-218-36x6.png 36w, https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-218-48x8.png 48w\" sizes=\"auto, (max-width: 210px) 100vw, 210px\" \/><\/a><figcaption>Macro DA#: Botones de funciones comunes<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Com\u00fanmente aplicado a hojas de Entidad (Obtener), Entidad (Conjunto), Atributo (Obtener) y Atributo (Conjunto).<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"2.1.1._Select_Model(\ubaa8\ub378_\uc120\ud0dd)\"><span class=\"ez-toc-section\" id=\"211_Select_Model%EB%AA%A8%EB%8D%B8_%EC%84%A0%ED%83%9D\"><\/span>2.1.1. Seleccionar modelo<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-219.png\"><img loading=\"lazy\" decoding=\"async\" width=\"695\" height=\"348\" src=\"https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-219.png\" alt=\"DA# Macro: \uacf5\ud1b5\uae30\ub2a5-Select Model\" class=\"wp-image-11696\" srcset=\"https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-219.png 695w, https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-219-300x150.png 300w, https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-219-18x9.png 18w, https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-219-24x12.png 24w, https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-219-36x18.png 36w, https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-219-48x24.png 48w\" sizes=\"auto, (max-width: 695px) 100vw, 695px\" \/><\/a><figcaption>Macro DA#: Funci\u00f3n com\u00fan-Seleccionar modelo<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Para ejecutar las funciones proporcionadas por cada hoja, la ventana &quot;Seleccionar modelo&quot; debe estar abierta.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Agregar archivo de modelo: agregue un archivo de modelo para ejecutar la macro. Puede seleccionar y agregar varios archivos en un directorio, o puede continuar agregando varios archivos en otro directorio.<\/li><li>Agregar modelo abierto: si se est\u00e1 ejecutando DA#, agregue el modelo actualmente abierto a DA#. Tambi\u00e9n puede agregar modelos que a\u00fan no se han guardado.<\/li><li>Guardar y cerrar: esta es una opci\u00f3n para guardar y cerrar cuando se completa el procesamiento de un archivo mientras se ejecuta Macro a su vez para los archivos de modelo agregados a la lista. Si est\u00e1 marcado, abre cada archivo, lo procesa, lo guarda y lo cierra. Si no est\u00e1 marcado, se abre y procesa sin guardar. Si hay muchos archivos de modelo para procesar, mantener abiertos los archivos de modelo consumir\u00e1 mucha memoria, por lo que se recomienda marcar la opci\u00f3n &quot;Guardar y cerrar&quot;. La funci\u00f3n Obtener opera solo para cerrar sin guardar.<\/li><li>Inicializar lista: elimine todos los archivos de modelo agregados a la lista.<\/li><li>Eliminar archivos seleccionados: elimina solo los archivos seleccionados de la lista. (May\u00fas + clic para seleccionar varios archivos consecutivos, o Ctrl + clic para seleccionar y eliminar varios archivos no contiguos)<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"2.1.2._Clear_List\"><span class=\"ez-toc-section\" id=\"212_Clear_List\"><\/span>2.1.2. Limpiar lista<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p>DA# Elimina el contenido impreso en la hoja de Excel como resultado de la ejecuci\u00f3n de la Macro.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"2.2._Entity_Get\/Set\"><span class=\"ez-toc-section\" id=\"22_DA_Macro_Entity_GetSet\"><\/span>2.2. DA# Macro Entidad Obtener\/Establecer<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"2.2.1._Entity_Get\"><span class=\"ez-toc-section\" id=\"221_Entity_Get\"><\/span>2.2.1. Obtener entidad<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-220.png\"><img loading=\"lazy\" decoding=\"async\" width=\"938\" height=\"497\" src=\"https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-220.png\" alt=\"DA# Macro \uae30\ub2a5: Entity(Get)\" class=\"wp-image-11697\" srcset=\"https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-220.png 938w, https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-220-300x159.png 300w, https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-220-768x407.png 768w, https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-220-18x10.png 18w, https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-220-24x13.png 24w, https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-220-36x19.png 36w, https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-220-48x25.png 48w\" sizes=\"auto, (max-width: 938px) 100vw, 938px\" \/><\/a><figcaption>Funci\u00f3n macro DA#: Entidad (Obtener)<\/figcaption><\/figure>\n<\/div>\n\n\n<ul class=\"wp-block-list\"><li>Obtener entidad: abre los modelos seleccionados en la ventana &quot;Seleccionar modelo&quot; uno tras otro y trae la informaci\u00f3n de atributos de todas las entidades a Excel. En este momento, solo se importan los elementos de atributo seleccionados en la l\u00ednea 3 &quot;Obtener destino por elemento (S\/N)&quot;. Si el elemento no es absolutamente necesario, puede establecer el objetivo en &quot;N&quot; para acelerar el tiempo de ejecuci\u00f3n.<\/li><li>La informaci\u00f3n de atributos de la entidad importada a Excel es la siguiente.<ul><li>nombre del modelo<\/li><li>nombre de la entidad<\/li><li>nombre de la tabla<\/li><li>sin\u00f3nimo<\/li><li>nombre auxiliar<\/li><li>Propietario de la base de datos<\/li><li>Clasificaci\u00f3n: Una de Clave, Principal, Acci\u00f3n o Ninguna<\/li><li>Nivel<\/li><li>Etapa: esencial o pr\u00e1ctica<\/li><li>Tipo: Uno de Normal, Adicional, Drop, Externo, Pseudo<\/li><li>Estandarizaci\u00f3n: una de herencia, objetivo o no objetivo<\/li><li>situaci\u00f3n<\/li><li>ciclo de ocurrencia<\/li><li>cantidad mensual<\/li><li>Per\u00edodo de retenci\u00f3n (meses)<\/li><li>n\u00famero total de casos<\/li><li>Justicia<\/li><li>formulario de procesamiento de datos<\/li><li>Unicidad<\/li><li>Nota<\/li><li>Etiqueta<\/li><\/ul><\/li><li>Copiar a conjunto: copie el nombre del modelo y el nombre de la entidad importados por &quot;Obtener entidad&quot; a la hoja &quot;Entidad (conjunto)&quot;.<\/li><li>Valores de propiedad definida por el usuario (UDP) definidos en entidades Puede importarlo ingresando el nombre UDP en la l\u00ednea 4 en . El nombre UDP debe ingresarse correctamente. Si no hay UDP definido en el modelo seleccionado o no hay un nombre UDP coincidente, el valor UDP no se importa.<\/li><li>Precauciones<ul><li>La columna X donde comienza la entrada UDP no debe eliminarse.<\/li><li>Los elementos UDP despu\u00e9s de la columna Y se pueden agregar\/eliminar y se puede cambiar el orden.<\/li><li>No puede agregar\/eliminar\/reordenar elementos en las columnas A a V y la columna W en blanco.<\/li><\/ul><\/li><\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-221.png\"><img loading=\"lazy\" decoding=\"async\" width=\"938\" height=\"497\" src=\"https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-221.png\" alt=\"DA# Macro \uae30\ub2a5: Entity(Get) - UDP\" class=\"wp-image-11698\" srcset=\"https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-221.png 938w, https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-221-300x159.png 300w, https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-221-768x407.png 768w, https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-221-18x10.png 18w, https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-221-24x13.png 24w, https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-221-36x19.png 36w, https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-221-48x25.png 48w\" sizes=\"auto, (max-width: 938px) 100vw, 938px\" \/><\/a><figcaption>Funci\u00f3n macro DA#: Entidad (Obtener) \u2013 UDP<\/figcaption><\/figure>\n<\/div>\n\n\n<h4 class=\"wp-block-heading\" id=\"2.2.2._Entity_Set\"><span class=\"ez-toc-section\" id=\"222_Entity_Set\"><\/span>2.2.2. Conjunto de entidades<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-222.png\"><img loading=\"lazy\" decoding=\"async\" width=\"938\" height=\"497\" src=\"https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-222.png\" alt=\"DA# Macro \uae30\ub2a5: Entity(Set)\" class=\"wp-image-11699\" srcset=\"https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-222.png 938w, https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-222-300x159.png 300w, https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-222-768x407.png 768w, https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-222-18x10.png 18w, https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-222-24x13.png 24w, https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-222-36x19.png 36w, https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-222-48x25.png 48w\" sizes=\"auto, (max-width: 938px) 100vw, 938px\" \/><\/a><figcaption>DA# Macro Funci\u00f3n: Entidad (Conjunto)<\/figcaption><\/figure>\n<\/div>\n\n\n<ul class=\"wp-block-list\"><li>Valor est\u00e1ndar: seleccione si buscar la entidad de destino que se cambiar\u00e1 en la columna B (nombre del modelo) por &quot;nombre de la entidad&quot; o &quot;nombre de la tabla&quot;.<\/li><li>Modo de adici\u00f3n: a\u00f1ade el contenido escrito en la hoja de Excel al valor actual de los elementos &quot;Definici\u00f3n&quot;, &quot;Tipo de procesamiento de datos&quot;, &quot;Elemento especial&quot; y &quot;Nota&quot; entre las caracter\u00edsticas de la entidad. Cabe se\u00f1alar que esto no se aplica a todos los art\u00edculos.<\/li><li>La informaci\u00f3n de propiedad de la entidad que se puede cambiar es la siguiente. Las propiedades &#039;clasificaci\u00f3n&#039;, &#039;nivel&#039;, &#039;tipo&#039; y &#039;normalizaci\u00f3n&#039; deben escribirse con uno de los valores predefinidos.<ul><li>nombre de la entidad<\/li><li>nombre de la tabla<\/li><li>sin\u00f3nimo<\/li><li>nombre auxiliar<\/li><li>Propietario de la base de datos<\/li><li>Clasificaci\u00f3n: Una de Clave, Principal, Acci\u00f3n o Ninguna<\/li><li>Nivel<\/li><li>Etapa: esencial o pr\u00e1ctica<\/li><li>Tipo: Uno de Normal, Adicional, Drop, Externo, Pseudo<\/li><li>Estandarizaci\u00f3n: una de herencia, objetivo o no objetivo<\/li><li>situaci\u00f3n<\/li><li>ciclo de ocurrencia<\/li><li>cantidad mensual<\/li><li>Per\u00edodo de retenci\u00f3n (meses)<\/li><li>n\u00famero total de casos<\/li><li>Justicia<\/li><li>formulario de procesamiento de datos<\/li><li>Unicidad<\/li><li>Nota<\/li><li>Etiqueta<\/li><\/ul><\/li><li>Establecer entidad: abre los modelos seleccionados en la ventana &quot;Seleccionar modelo&quot; uno tras otro y refleja la informaci\u00f3n de propiedad de la entidad escrita en la hoja de Excel para el modelo y la entidad. Similar a la funci\u00f3n &quot;Obtener entidad&quot;, solo se refleja el elemento de atributo seleccionado en la l\u00ednea 3 &quot;Obtener objeto por elemento (S\/N)&quot;.<\/li><li>El valor UDP de la entidad a cambiar es Escribir en Si el nombre UDP no coincide exactamente, el valor no se refleja.<\/li><li>Precauciones<ul><li>La columna Z, donde comienza la entrada UDP, no debe eliminarse.<\/li><li>Los elementos UDP despu\u00e9s de la columna Z se pueden agregar\/eliminar y se puede cambiar el orden.<\/li><li>No puede agregar\/eliminar\/reordenar elementos de la columna A a la columna X y dejar en blanco la columna Y.<\/li><\/ul><\/li><\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-223.png\"><img loading=\"lazy\" decoding=\"async\" width=\"938\" height=\"497\" src=\"https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-223.png\" alt=\"DA# Macro \uae30\ub2a5: Entity(Set) - UDP\" class=\"wp-image-11700\" srcset=\"https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-223.png 938w, https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-223-300x159.png 300w, https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-223-768x407.png 768w, https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-223-18x10.png 18w, https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-223-24x13.png 24w, https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-223-36x19.png 36w, https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-223-48x25.png 48w\" sizes=\"auto, (max-width: 938px) 100vw, 938px\" \/><\/a><figcaption>Funci\u00f3n macro DA#: Entidad (Conjunto) \u2013 UDP<\/figcaption><\/figure>\n<\/div>\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\"\/>\n\n\n\n<p>Hasta ahora, hemos visto funciones comunes y funciones Get\/Set de entidad entre las funciones de macro DA#. A continuaci\u00f3n, veremos la funci\u00f3n Obtener\/Establecer atributo.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>&lt;&lt;&nbsp;<strong>Lista de art\u00edculos relacionados<\/strong>&nbsp;&gt;&gt;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/prodskill.com\/es\/da-macro-overview\/\">Macro DA#(1): DA#, API DA#, descripci\u00f3n general de la macro DA#<\/a><\/li><li><a href=\"https:\/\/prodskill.com\/es\/da-macro-function-common-entity-get-set\/\">Macro DA# (2): Funci\u00f3n macro DA# (1) - Funci\u00f3n com\u00fan, Entidad Get\/Set<\/a><\/li><li><a href=\"https:\/\/prodskill.com\/es\/da-macro-function-attribute-get-set\/\">Macro DA# (3): Funci\u00f3n de macro DA# (2) - Obtener\/Establecer atributo<\/a><\/li><li><a href=\"https:\/\/prodskill.com\/es\/da-macro-function-reverse\/\">Macro DA# (4): Funci\u00f3n macro DA# (3) -Reversa<\/a><\/li><li><a href=\"https:\/\/prodskill.com\/es\/da-macro-usage-notes\/\">Macro DA#(5): Notas\/notas de uso, descargas, funciones que se agregar\u00e1n en el futuro, notas<\/a><\/li><li><a href=\"https:\/\/prodskill.com\/es\/da-macro-modeler-api\/\">Macro DA#(6): API del modelador DA#<\/a><\/li><li><a href=\"https:\/\/prodskill.com\/es\/da-macro-demo-video-youtube\/\">Video de demostraci\u00f3n de la funci\u00f3n macro DA# (YouTube)<\/a><\/li><li><a href=\"https:\/\/prodskill.com\/es\/da-macro-toc\/\">Contenido de la descripci\u00f3n de la macro DA#, descarga<\/a><\/li><\/ul>","protected":false},"excerpt":{"rendered":"<p>En este art\u00edculo, analizamos la funci\u00f3n com\u00fan de macro Da# Entity Get\/Set. Esta es una continuaci\u00f3n del art\u00edculo anterior. DA# Macro(1): DA#, DA# API, DA# Macro (Macro) Descripci\u00f3n general 2. Funci\u00f3n de macro DA# La funci\u00f3n de macro DA# se divide en gran medida en funciones comunes, Obtener\/Establecer entidad, Obtener\/Establecer atributo e Invertir. 2.1. DA# Macro funci\u00f3n com\u00fan...<\/p>","protected":false},"author":1,"featured_media":11697,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[17,73,109,110,111],"class_list":["post-11694","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-da-macro","tag-vba","tag-excel-vba","tag-da","tag-api","tag-da-macro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DA# Macro(2): DA# Macro(\ub9e4\ud06c\ub85c) \uae30\ub2a5(1)-\uacf5\ud1b5\uae30\ub2a5, Entity Get\/Set - \uc0dd\uc0b0\uc131 Skill<\/title>\n<meta name=\"description\" content=\"Da# Macro \uacf5\ud1b5\uae30\ub2a5 Entity Get\/Set \uae30\ub2a5\uc5d0 \ub300\ud574 \uc0b4\ud3b4\ubcf8\ub2e4. \uacf5\ud1b5\uae30\ub2a5\uc740 Select Model(\ubaa8\ub378 \uc120\ud0dd), Clear List\ub85c \uc81c\uacf5\ub418\uace0, Entity Get\/Set \uae30\ub2a5\uc740 \uc120\ud0dd\ud55c \ubaa8\ub378\uc758 \uc5d4\ud130\ud2f0 \ud2b9\uc131\uc815\ubcf4\ub97c \uac00\uc838\uc624\uac70\ub098 \uc124\uc815\ud55c\ub2e4.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/prodskill.com\/es\/da-macro-function-common-entity-get-set\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DA# Macro(2): DA# Macro(\ub9e4\ud06c\ub85c) \uae30\ub2a5(1)-\uacf5\ud1b5\uae30\ub2a5, Entity Get\/Set - \uc0dd\uc0b0\uc131 Skill\" \/>\n<meta property=\"og:description\" content=\"Da# Macro \uacf5\ud1b5\uae30\ub2a5 Entity Get\/Set \uae30\ub2a5\uc5d0 \ub300\ud574 \uc0b4\ud3b4\ubcf8\ub2e4. \uacf5\ud1b5\uae30\ub2a5\uc740 Select Model(\ubaa8\ub378 \uc120\ud0dd), Clear List\ub85c \uc81c\uacf5\ub418\uace0, Entity Get\/Set \uae30\ub2a5\uc740 \uc120\ud0dd\ud55c \ubaa8\ub378\uc758 \uc5d4\ud130\ud2f0 \ud2b9\uc131\uc815\ubcf4\ub97c \uac00\uc838\uc624\uac70\ub098 \uc124\uc815\ud55c\ub2e4.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/prodskill.com\/es\/da-macro-function-common-entity-get-set\/\" \/>\n<meta property=\"og:site_name\" content=\"\uc0dd\uc0b0\uc131 Skill\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-28T07:42:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-10T12:01:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-220.png\" \/>\n\t<meta property=\"og:image:width\" content=\"938\" \/>\n\t<meta property=\"og:image:height\" content=\"497\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Zerom\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Zerom\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/prodskill.com\\\/da-macro-function-common-entity-get-set\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prodskill.com\\\/da-macro-function-common-entity-get-set\\\/\"},\"author\":{\"name\":\"Zerom\",\"@id\":\"https:\\\/\\\/prodskill.com\\\/ko\\\/#\\\/schema\\\/person\\\/bbad0870c78008c82edbe0960fe768bd\"},\"headline\":\"DA# Macro(2): DA# Macro(\ub9e4\ud06c\ub85c) \uae30\ub2a5(1)-\uacf5\ud1b5\uae30\ub2a5, Entity Get\\\/Set\",\"datePublished\":\"2022-09-28T07:42:05+00:00\",\"dateModified\":\"2022-10-10T12:01:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/prodskill.com\\\/da-macro-function-common-entity-get-set\\\/\"},\"wordCount\":314,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/prodskill.com\\\/ko\\\/#\\\/schema\\\/person\\\/bbad0870c78008c82edbe0960fe768bd\"},\"image\":{\"@id\":\"https:\\\/\\\/prodskill.com\\\/da-macro-function-common-entity-get-set\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prodskill.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/image-220.png\",\"keywords\":[\"\uc5d1\uc140VBA\",\"Excel VBA\",\"DA#\",\"API\",\"DA# Macro\"],\"articleSection\":[\"DA# Macro\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/prodskill.com\\\/da-macro-function-common-entity-get-set\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/prodskill.com\\\/da-macro-function-common-entity-get-set\\\/\",\"url\":\"https:\\\/\\\/prodskill.com\\\/da-macro-function-common-entity-get-set\\\/\",\"name\":\"DA# Macro(2): DA# Macro(\ub9e4\ud06c\ub85c) \uae30\ub2a5(1)-\uacf5\ud1b5\uae30\ub2a5, Entity Get\\\/Set - \uc0dd\uc0b0\uc131 Skill\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/prodskill.com\\\/ko\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/prodskill.com\\\/da-macro-function-common-entity-get-set\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/prodskill.com\\\/da-macro-function-common-entity-get-set\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/prodskill.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/image-220.png\",\"datePublished\":\"2022-09-28T07:42:05+00:00\",\"dateModified\":\"2022-10-10T12:01:58+00:00\",\"description\":\"Da# Macro \uacf5\ud1b5\uae30\ub2a5 Entity Get\\\/Set \uae30\ub2a5\uc5d0 \ub300\ud574 \uc0b4\ud3b4\ubcf8\ub2e4. \uacf5\ud1b5\uae30\ub2a5\uc740 Select Model(\ubaa8\ub378 \uc120\ud0dd), Clear List\ub85c \uc81c\uacf5\ub418\uace0, Entity Get\\\/Set \uae30\ub2a5\uc740 \uc120\ud0dd\ud55c \ubaa8\ub378\uc758 \uc5d4\ud130\ud2f0 \ud2b9\uc131\uc815\ubcf4\ub97c \uac00\uc838\uc624\uac70\ub098 \uc124\uc815\ud55c\ub2e4.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/prodskill.com\\\/da-macro-function-common-entity-get-set\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/prodskill.com\\\/da-macro-function-common-entity-get-set\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/prodskill.com\\\/da-macro-function-common-entity-get-set\\\/#primaryimage\",\"url\":\"https:\\\/\\\/prodskill.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/image-220.png\",\"contentUrl\":\"https:\\\/\\\/prodskill.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/image-220.png\",\"width\":938,\"height\":497},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/prodskill.com\\\/da-macro-function-common-entity-get-set\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/prodskill.com\\\/ko\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DA# Macro(2): DA# Macro(\ub9e4\ud06c\ub85c) \uae30\ub2a5(1)-\uacf5\ud1b5\uae30\ub2a5, Entity Get\\\/Set\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/prodskill.com\\\/ko\\\/#website\",\"url\":\"https:\\\/\\\/prodskill.com\\\/ko\\\/\",\"name\":\"\uc0dd\uc0b0\uc131 Skill\",\"description\":\"Meta Thinking, Meta Working\",\"publisher\":{\"@id\":\"https:\\\/\\\/prodskill.com\\\/ko\\\/#\\\/schema\\\/person\\\/bbad0870c78008c82edbe0960fe768bd\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/prodskill.com\\\/ko\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/prodskill.com\\\/ko\\\/#\\\/schema\\\/person\\\/bbad0870c78008c82edbe0960fe768bd\",\"name\":\"Zerom\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/prodskill.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/productivity_clockgear.png\",\"url\":\"https:\\\/\\\/prodskill.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/productivity_clockgear.png\",\"contentUrl\":\"https:\\\/\\\/prodskill.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/productivity_clockgear.png\",\"width\":512,\"height\":512,\"caption\":\"Zerom\"},\"logo\":{\"@id\":\"https:\\\/\\\/prodskill.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/productivity_clockgear.png\"},\"url\":\"https:\\\/\\\/prodskill.com\\\/es\\\/author\\\/proda\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Macro DA# (2): Funci\u00f3n macro DA# (1) - Funci\u00f3n com\u00fan, obtenci\u00f3n\/configuraci\u00f3n de entidad - Habilidad de productividad","description":"Analicemos las funciones comunes de la macro Da#, Obtener\/Establecer entidad. Estas funciones incluyen Seleccionar modelo y Borrar lista, y la funci\u00f3n Obtener\/Establecer entidad recupera o establece la informaci\u00f3n de los atributos de la entidad para el modelo seleccionado.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/prodskill.com\/es\/da-macro-function-common-entity-get-set\/","og_locale":"es_ES","og_type":"article","og_title":"DA# Macro(2): DA# Macro(\ub9e4\ud06c\ub85c) \uae30\ub2a5(1)-\uacf5\ud1b5\uae30\ub2a5, Entity Get\/Set - \uc0dd\uc0b0\uc131 Skill","og_description":"Da# Macro \uacf5\ud1b5\uae30\ub2a5 Entity Get\/Set \uae30\ub2a5\uc5d0 \ub300\ud574 \uc0b4\ud3b4\ubcf8\ub2e4. \uacf5\ud1b5\uae30\ub2a5\uc740 Select Model(\ubaa8\ub378 \uc120\ud0dd), Clear List\ub85c \uc81c\uacf5\ub418\uace0, Entity Get\/Set \uae30\ub2a5\uc740 \uc120\ud0dd\ud55c \ubaa8\ub378\uc758 \uc5d4\ud130\ud2f0 \ud2b9\uc131\uc815\ubcf4\ub97c \uac00\uc838\uc624\uac70\ub098 \uc124\uc815\ud55c\ub2e4.","og_url":"https:\/\/prodskill.com\/es\/da-macro-function-common-entity-get-set\/","og_site_name":"\uc0dd\uc0b0\uc131 Skill","article_published_time":"2022-09-28T07:42:05+00:00","article_modified_time":"2022-10-10T12:01:58+00:00","og_image":[{"width":938,"height":497,"url":"https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-220.png","type":"image\/png"}],"author":"Zerom","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Zerom","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/prodskill.com\/da-macro-function-common-entity-get-set\/#article","isPartOf":{"@id":"https:\/\/prodskill.com\/da-macro-function-common-entity-get-set\/"},"author":{"name":"Zerom","@id":"https:\/\/prodskill.com\/ko\/#\/schema\/person\/bbad0870c78008c82edbe0960fe768bd"},"headline":"DA# Macro(2): DA# Macro(\ub9e4\ud06c\ub85c) \uae30\ub2a5(1)-\uacf5\ud1b5\uae30\ub2a5, Entity Get\/Set","datePublished":"2022-09-28T07:42:05+00:00","dateModified":"2022-10-10T12:01:58+00:00","mainEntityOfPage":{"@id":"https:\/\/prodskill.com\/da-macro-function-common-entity-get-set\/"},"wordCount":314,"commentCount":0,"publisher":{"@id":"https:\/\/prodskill.com\/ko\/#\/schema\/person\/bbad0870c78008c82edbe0960fe768bd"},"image":{"@id":"https:\/\/prodskill.com\/da-macro-function-common-entity-get-set\/#primaryimage"},"thumbnailUrl":"https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-220.png","keywords":["\uc5d1\uc140VBA","Excel VBA","DA#","API","DA# Macro"],"articleSection":["DA# Macro"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/prodskill.com\/da-macro-function-common-entity-get-set\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/prodskill.com\/da-macro-function-common-entity-get-set\/","url":"https:\/\/prodskill.com\/da-macro-function-common-entity-get-set\/","name":"Macro DA# (2): Funci\u00f3n macro DA# (1) - Funci\u00f3n com\u00fan, obtenci\u00f3n\/configuraci\u00f3n de entidad - Habilidad de productividad","isPartOf":{"@id":"https:\/\/prodskill.com\/ko\/#website"},"primaryImageOfPage":{"@id":"https:\/\/prodskill.com\/da-macro-function-common-entity-get-set\/#primaryimage"},"image":{"@id":"https:\/\/prodskill.com\/da-macro-function-common-entity-get-set\/#primaryimage"},"thumbnailUrl":"https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-220.png","datePublished":"2022-09-28T07:42:05+00:00","dateModified":"2022-10-10T12:01:58+00:00","description":"Analicemos las funciones comunes de la macro Da#, Obtener\/Establecer entidad. Estas funciones incluyen Seleccionar modelo y Borrar lista, y la funci\u00f3n Obtener\/Establecer entidad recupera o establece la informaci\u00f3n de los atributos de la entidad para el modelo seleccionado.","breadcrumb":{"@id":"https:\/\/prodskill.com\/da-macro-function-common-entity-get-set\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/prodskill.com\/da-macro-function-common-entity-get-set\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/prodskill.com\/da-macro-function-common-entity-get-set\/#primaryimage","url":"https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-220.png","contentUrl":"https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/image-220.png","width":938,"height":497},{"@type":"BreadcrumbList","@id":"https:\/\/prodskill.com\/da-macro-function-common-entity-get-set\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prodskill.com\/ko\/"},{"@type":"ListItem","position":2,"name":"DA# Macro(2): DA# Macro(\ub9e4\ud06c\ub85c) \uae30\ub2a5(1)-\uacf5\ud1b5\uae30\ub2a5, Entity Get\/Set"}]},{"@type":"WebSite","@id":"https:\/\/prodskill.com\/ko\/#website","url":"https:\/\/prodskill.com\/ko\/","name":"Habilidades de productividad","description":"Meta Pensamiento, Meta Trabajo","publisher":{"@id":"https:\/\/prodskill.com\/ko\/#\/schema\/person\/bbad0870c78008c82edbe0960fe768bd"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/prodskill.com\/ko\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/prodskill.com\/ko\/#\/schema\/person\/bbad0870c78008c82edbe0960fe768bd","name":"Cerom","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/productivity_clockgear.png","url":"https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/productivity_clockgear.png","contentUrl":"https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/productivity_clockgear.png","width":512,"height":512,"caption":"Zerom"},"logo":{"@id":"https:\/\/prodskill.com\/wp-content\/uploads\/2022\/09\/productivity_clockgear.png"},"url":"https:\/\/prodskill.com\/es\/author\/proda\/"}]}},"_links":{"self":[{"href":"https:\/\/prodskill.com\/es\/wp-json\/wp\/v2\/posts\/11694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prodskill.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prodskill.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prodskill.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prodskill.com\/es\/wp-json\/wp\/v2\/comments?post=11694"}],"version-history":[{"count":0,"href":"https:\/\/prodskill.com\/es\/wp-json\/wp\/v2\/posts\/11694\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prodskill.com\/es\/wp-json\/wp\/v2\/media\/11697"}],"wp:attachment":[{"href":"https:\/\/prodskill.com\/es\/wp-json\/wp\/v2\/media?parent=11694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prodskill.com\/es\/wp-json\/wp\/v2\/categories?post=11694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prodskill.com\/es\/wp-json\/wp\/v2\/tags?post=11694"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}